{"id":8149,"date":"2020-02-19T09:30:06","date_gmt":"2020-02-19T08:30:06","guid":{"rendered":"https:\/\/www.mbi-geodata.com\/de\/?p=8149"},"modified":"2020-02-19T09:53:50","modified_gmt":"2020-02-19T08:53:50","slug":"michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start","status":"publish","type":"post","link":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/","title":{"rendered":"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start"},"content":{"rendered":"<p><a href=\"https:\/\/www.mb-micromarketing.de\/\"><img decoding=\"async\" class=\"alignnone wp-image-8151 size-full\" src=\"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg\" alt=\"Michael Bauer Micromarketing\" width=\"725\" height=\"484\" srcset=\"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg 725w, https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM-300x200.jpg 300w, https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM-88x59.jpg 88w\" sizes=\"(max-width: 725px) 100vw, 725px\" \/><\/a><\/p>\n<p>Erfahrene Spezialisten aus dem Bereich Micromarketing er\u00f6ffnen unter dem Dach von Michael Bauer und unter Beteiligung des SINUS-Instituts das neue Unternehmen in D\u00fcsseldorf, mit Sabine Ahlemeier und Rolf K\u00fcppers als gesch\u00e4ftsf\u00fchrende Gesellschafter.<\/p>\n<p>Mit <a href=\"https:\/\/www.mb-micromarketing.de\/\">Michael Bauer Micromarketing<\/a> ist jetzt die dritte S\u00e4ule der Michael Bauer Gruppe aufgebaut worden und erg\u00e4nzt das bestehende Portfolio um feinr\u00e4umige Markt- und Zielgruppendaten sowie qualitativ hochwertige Standort- und Zielgruppenanalysen.<\/p>\n<p>Nachdem Michael Bauer Research seit 15 Jahren mit Markt- und Kaufkraftdaten erfolgreich am Markt ist und Michael Bauer International seit 10 Jahren einen Standard setzt in der Bereitstellung Internationaler Markt- und Geodaten, wurde jetzt zusammen mit den Milieu-Experten von SINUS der neue Spezialist f\u00fcr Customer und Location Intelligence gegr\u00fcndet.<\/p>\n<p>\u201eBasierend auf der microgeographischen Datenbasis sind die Sinus-Milieus\u00ae, die \u00dcbertragung der Best4Planning in den Raum und Bewegungsdaten unsere wichtigsten Instrumente, die zusammen mit unserer Analysekompetenz dazu beitragen, dass unsere Kunden ihre Zielgruppen besser kennen lernen und verstehen\u201c, sagt Gesch\u00e4ftsf\u00fchrer Rolf K\u00fcppers.<\/p>\n<p>\u201eM\u00f6glich ist diese geballte Expertise durch Spezialisten, die wir von Anfang an f\u00fcr das junge Unternehmen gewinnen konnten, und die sich insbesondere mit intelligenter Datenverkn\u00fcpfung auskennen und auf eine jahrelange Erfahrung bei der \u00dcbertragung von Marktforschungsdaten in das Geomarketing zur\u00fcck greifen k\u00f6nnen\u201c, erg\u00e4nzt Gesch\u00e4ftsf\u00fchrerin Sabine Ahlemeier.<\/p>\n<p>Somit ist Michael Bauer Micromarketing, kurz MBM genannt, die Daten- und Analysemanufaktur, die unter dem Motto \u201eFinest Data and Analytics\u201c Unternehmen dabei unterst\u00fctzt, sichere Standortentscheidungen zu treffen und zielgruppengerechte Werbung \u00fcber die optimalen Werbekan\u00e4le auszusteuern \u2013 mit dem Ziel, das richtige Produkt am richtigen Ort zur richtigen Zeit zu platzieren.<\/p>\n<p><strong>\u00dcber MB-Research<\/strong><\/p>\n<p>Die Michael Bauer Research GmbH, N\u00fcrnberg besteht seit dem 27. Januar 2004.<\/p>\n<p>Sie ist auf die Erstellung kleinr\u00e4umiger Regionalmarktdaten, wie z.B. Kaufkraftkennziffern, auf administrativer, microgeographischer und postalischer Ebene auf der ganzen Welt spezialisiert.<br \/>\nPassend dazu erstellt MB-Research kompatible Digitale Grenzen f\u00fcr den Einsatz in einem GIS, CRM oder f\u00fcr Business-Intelligence L\u00f6sungen. Die Kunden kommen dabei aus den unterschiedlichsten Bereichen wie Einzelhandel, Konsumg\u00fcter, Investitionsg\u00fcter, Banken, Immobilienresearch, Automobilindustrie, u.v.a.<\/p>\n<p><strong>\u00dcber MB-International<\/strong><\/p>\n<p>Die Kernkompetenz von Michael Bauer International GmbH ist ein weit reichendes Angebot an internationalen Markt- und Geodaten auf verschiedenen Gebietsebenen (Postleitzahlebene, administrative Ebenen, feinr\u00e4umige Gebietsebenen).<\/p>\n<p>Hierzu z\u00e4hlen soziodemographische Daten wie z.B. Bev\u00f6lkerung, Haushalte, Altersstruktur sowie Zielgruppen und verschiedene Kaufkraftkennziffern und die dazu passenden Gebietsgrenzen. Detaillierte Stra\u00dfenkarten, kundenspezifisch aufbereitete Mobilit\u00e4tsdaten, Points of Interest und Geokodierungsdienstleistungen runden das globale Angebot ab.<\/p>\n<p>Egal ob Kunden national oder international t\u00e4tig sind, vergleichbare, homogene Daten sind die Grundlage f\u00fcr gute Planungen. Nur mit einer inhaltlich wie geometrisch einheitlichen Datenbasis k\u00f6nnen Analysen durchgef\u00fchrt werden, die letztendlich eine fundierte Entscheidungsgrundlage darstellen.<\/p>\n<p><strong>\u00dcber SINUS<\/strong><\/p>\n<p>Die SINUS Markt- und Sozialforschung GmbH mit Standorten in Heidelberg und Berlin, ist seit \u00fcber 40 Jahren Spezialist f\u00fcr psychologische und sozialwissenschaftliche Forschung und Beratung. Das Institut entwickelt Strategien f\u00fcr Unternehmen und Institutionen, die den soziokulturellen Wandel als Erfolgsfaktor nutzen.<\/p>\n<p>Ein zentrales Tool daf\u00fcr sind die Sinus-Milieus\u00ae &#8211; ein Gesellschafts- und Zielgruppenmodell, das Menschen nach ihren Lebenswelten in \u201eGruppen Gleichgesinnter\u201c zusammenfasst. Die Sinus-Milieus\u00ae z\u00e4hlen seit Jahrzehnten zu den bekanntesten und einflussreichsten Segmentationsans\u00e4tzen und sind mittlerweile f\u00fcr \u00fcber 40 L\u00e4nder verf\u00fcgbar.<\/p>\n<p>SINUS kooperiert eng mit dem Schwesterunternehmen INTEGRAL Marktforschung in Wien, \u00d6sterreich.<\/p>\n<div class=\"shariff shariff-align-center shariff-widget-align-left\"><div class=\"ShariffHeadline\"><h3 class=\"shariff_headline\">Teilen<\/h3><\/div><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.mbi-geodata.com%2Fde%2F2020%2F02%2F19%2Fmichael-bauer-micromarketing-geht-in-duesseldorf-an-den-start%2F&text=Michael%20Bauer%20Micromarketing%20geht%20in%20D%C3%BCsseldorf%20an%20den%20Start&via=MBIgeodata\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.mbi-geodata.com%2Fde%2F2020%2F02%2F19%2Fmichael-bauer-micromarketing-geht-in-duesseldorf-an-den-start%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.mbi-geodata.com%2Fde%2F2020%2F02%2F19%2Fmichael-bauer-micromarketing-geht-in-duesseldorf-an-den-start%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.mbi-geodata.com%2Fde%2F2020%2F02%2F19%2Fmichael-bauer-micromarketing-geht-in-duesseldorf-an-den-start%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fwww.mbi-geodata.com%2Fde%2F2020%2F02%2F19%2Fmichael-bauer-micromarketing-geht-in-duesseldorf-an-den-start%2F&subject=Michael%20Bauer%20Micromarketing%20geht%20in%20D%C3%BCsseldorf%20an%20den%20Start\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Erfahrene Spezialisten aus dem Bereich Micromarketing er\u00f6ffnen unter dem Dach von Michael Bauer und unter Beteiligung des SINUS-Instituts das neue Unternehmen in D\u00fcsseldorf, mit Sabine Ahlemeier und Rolf K\u00fcppers als [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","ngg_post_thumbnail":0,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[119,120],"tags":[],"class_list":["post-8149","post","type-post","status-publish","format-standard","hentry","category-news","category-press"],"acf":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","mini":"","post-thumbnail":"","gform-image-choice-sm":"","gform-image-choice-md":"","gform-image-choice-lg":""},"post_excerpt_stackable_v2":"<p>Erfahrene Spezialisten aus dem Bereich Micromarketing er\u00f6ffnen unter dem Dach von Michael Bauer und unter Beteiligung des SINUS-Instituts das neue Unternehmen in D\u00fcsseldorf, mit Sabine Ahlemeier und Rolf K\u00fcppers als gesch\u00e4ftsf\u00fchrende Gesellschafter. Mit Michael Bauer Micromarketing ist jetzt die dritte S\u00e4ule der Michael Bauer Gruppe aufgebaut worden und erg\u00e4nzt das bestehende Portfolio um feinr\u00e4umige Markt- und Zielgruppendaten sowie qualitativ hochwertige Standort- und Zielgruppenanalysen. Nachdem Michael Bauer Research seit 15 Jahren mit Markt- und Kaufkraftdaten erfolgreich am Markt ist und Michael Bauer International seit 10 Jahren einen Standard setzt in der Bereitstellung Internationaler Markt- und Geodaten, wurde jetzt zusammen mit den&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/www.mbi-geodata.com\/de\/category\/news\/\" rel=\"category tag\">News<\/a>, <a href=\"https:\/\/www.mbi-geodata.com\/de\/category\/press\/\" rel=\"category tag\">Presse<\/a>","author_info_v2":{"name":"robertsyork","url":"https:\/\/www.mbi-geodata.com\/de\/author\/robertsyork\/"},"comments_num_v2":"0 comments","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start - MBI Weltweite Geodaten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start - MBI Weltweite Geodaten\" \/>\n<meta property=\"og:description\" content=\"Erfahrene Spezialisten aus dem Bereich Micromarketing er\u00f6ffnen unter dem Dach von Michael Bauer und unter Beteiligung des SINUS-Instituts das neue Unternehmen in D\u00fcsseldorf, mit Sabine Ahlemeier und Rolf K\u00fcppers als [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/\" \/>\n<meta property=\"og:site_name\" content=\"MBI Weltweite Geodaten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MBIgeodata\/?locale=de_DE\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T08:30:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-19T08:53:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg\" \/>\n<meta name=\"author\" content=\"robertsyork\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MBIgeodata\" \/>\n<meta name=\"twitter:site\" content=\"@MBIgeodata\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"robertsyork\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/\"},\"author\":{\"name\":\"robertsyork\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#\\\/schema\\\/person\\\/4263754d2fe44040566edad9c0cc9480\"},\"headline\":\"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start\",\"datePublished\":\"2020-02-19T08:30:06+00:00\",\"dateModified\":\"2020-02-19T08:53:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/\"},\"wordCount\":562,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/MBM.jpg\",\"articleSection\":[\"News\",\"Presse\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/\",\"url\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/\",\"name\":\"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start - MBI Weltweite Geodaten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/MBM.jpg\",\"datePublished\":\"2020-02-19T08:30:06+00:00\",\"dateModified\":\"2020-02-19T08:53:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/MBM.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/MBM.jpg\",\"width\":725,\"height\":484,\"caption\":\"Michael Bauer Micromarketing\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/2020\\\/02\\\/19\\\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/\",\"name\":\"MBI Weltweite Geodaten\",\"description\":\"Weltweit einheitlich und vergleichbar\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#organization\",\"name\":\"Michael Bauer International GmbH\",\"alternateName\":\"MBI\",\"url\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/07\\\/MBI_Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/07\\\/MBI_Logo.png\",\"width\":481,\"height\":482,\"caption\":\"Michael Bauer International GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MBIgeodata\\\/?locale=de_DE\",\"https:\\\/\\\/x.com\\\/MBIgeodata\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/michael-bauer-international-gmbh\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCSqLxdr6Dj1INWxeHuAB0Aw\\\/featured\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/michaelbauerinternationalgmbh\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/#\\\/schema\\\/person\\\/4263754d2fe44040566edad9c0cc9480\",\"name\":\"robertsyork\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa31ba9d41a756ecb43d5f0e86fa5210ae336b49390ebbd9b31329e8471fa6d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa31ba9d41a756ecb43d5f0e86fa5210ae336b49390ebbd9b31329e8471fa6d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa31ba9d41a756ecb43d5f0e86fa5210ae336b49390ebbd9b31329e8471fa6d5?s=96&d=mm&r=g\",\"caption\":\"robertsyork\"},\"url\":\"https:\\\/\\\/www.mbi-geodata.com\\\/de\\\/author\\\/robertsyork\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start - MBI Weltweite Geodaten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/","og_locale":"de_DE","og_type":"article","og_title":"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start - MBI Weltweite Geodaten","og_description":"Erfahrene Spezialisten aus dem Bereich Micromarketing er\u00f6ffnen unter dem Dach von Michael Bauer und unter Beteiligung des SINUS-Instituts das neue Unternehmen in D\u00fcsseldorf, mit Sabine Ahlemeier und Rolf K\u00fcppers als [&hellip;]","og_url":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/","og_site_name":"MBI Weltweite Geodaten","article_publisher":"https:\/\/www.facebook.com\/MBIgeodata\/?locale=de_DE","article_published_time":"2020-02-19T08:30:06+00:00","article_modified_time":"2020-02-19T08:53:50+00:00","og_image":[{"url":"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg","type":"","width":"","height":""}],"author":"robertsyork","twitter_card":"summary_large_image","twitter_creator":"@MBIgeodata","twitter_site":"@MBIgeodata","twitter_misc":{"Verfasst von":"robertsyork","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/#article","isPartOf":{"@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/"},"author":{"name":"robertsyork","@id":"https:\/\/www.mbi-geodata.com\/de\/#\/schema\/person\/4263754d2fe44040566edad9c0cc9480"},"headline":"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start","datePublished":"2020-02-19T08:30:06+00:00","dateModified":"2020-02-19T08:53:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/"},"wordCount":562,"publisher":{"@id":"https:\/\/www.mbi-geodata.com\/de\/#organization"},"image":{"@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg","articleSection":["News","Presse"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/","url":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/","name":"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start - MBI Weltweite Geodaten","isPartOf":{"@id":"https:\/\/www.mbi-geodata.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/#primaryimage"},"image":{"@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg","datePublished":"2020-02-19T08:30:06+00:00","dateModified":"2020-02-19T08:53:50+00:00","breadcrumb":{"@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/#primaryimage","url":"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg","contentUrl":"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2020\/02\/MBM.jpg","width":725,"height":484,"caption":"Michael Bauer Micromarketing"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mbi-geodata.com\/de\/2020\/02\/19\/michael-bauer-micromarketing-geht-in-duesseldorf-an-den-start\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mbi-geodata.com\/de\/"},{"@type":"ListItem","position":2,"name":"Michael Bauer Micromarketing geht in D\u00fcsseldorf an den Start"}]},{"@type":"WebSite","@id":"https:\/\/www.mbi-geodata.com\/de\/#website","url":"https:\/\/www.mbi-geodata.com\/de\/","name":"MBI Weltweite Geodaten","description":"Weltweit einheitlich und vergleichbar","publisher":{"@id":"https:\/\/www.mbi-geodata.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mbi-geodata.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mbi-geodata.com\/de\/#organization","name":"Michael Bauer International GmbH","alternateName":"MBI","url":"https:\/\/www.mbi-geodata.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mbi-geodata.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2022\/07\/MBI_Logo.png","contentUrl":"https:\/\/www.mbi-geodata.com\/de\/wp-content\/uploads\/sites\/2\/2022\/07\/MBI_Logo.png","width":481,"height":482,"caption":"Michael Bauer International GmbH"},"image":{"@id":"https:\/\/www.mbi-geodata.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MBIgeodata\/?locale=de_DE","https:\/\/x.com\/MBIgeodata","https:\/\/de.linkedin.com\/company\/michael-bauer-international-gmbh","https:\/\/www.youtube.com\/channel\/UCSqLxdr6Dj1INWxeHuAB0Aw\/featured","https:\/\/www.xing.com\/pages\/michaelbauerinternationalgmbh"]},{"@type":"Person","@id":"https:\/\/www.mbi-geodata.com\/de\/#\/schema\/person\/4263754d2fe44040566edad9c0cc9480","name":"robertsyork","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa31ba9d41a756ecb43d5f0e86fa5210ae336b49390ebbd9b31329e8471fa6d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa31ba9d41a756ecb43d5f0e86fa5210ae336b49390ebbd9b31329e8471fa6d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa31ba9d41a756ecb43d5f0e86fa5210ae336b49390ebbd9b31329e8471fa6d5?s=96&d=mm&r=g","caption":"robertsyork"},"url":"https:\/\/www.mbi-geodata.com\/de\/author\/robertsyork\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"mini":false,"post-thumbnail":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"robertsyork","author_link":"https:\/\/www.mbi-geodata.com\/de\/author\/robertsyork\/"},"uagb_comment_info":0,"uagb_excerpt":"Erfahrene Spezialisten aus dem Bereich Micromarketing er\u00f6ffnen unter dem Dach von Michael Bauer und unter Beteiligung des SINUS-Instituts das neue Unternehmen in D\u00fcsseldorf, mit Sabine Ahlemeier und Rolf K\u00fcppers als [&hellip;]","_links":{"self":[{"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/posts\/8149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/comments?post=8149"}],"version-history":[{"count":6,"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/posts\/8149\/revisions"}],"predecessor-version":[{"id":8156,"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/posts\/8149\/revisions\/8156"}],"wp:attachment":[{"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/media?parent=8149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/categories?post=8149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mbi-geodata.com\/de\/wp-json\/wp\/v2\/tags?post=8149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}